{"id":525,"date":"2025-01-15T23:42:23","date_gmt":"2025-01-15T22:42:23","guid":{"rendered":"https:\/\/nica.network\/?page_id=525"},"modified":"2026-01-22T14:39:51","modified_gmt":"2026-01-22T13:39:51","slug":"tohuwabohu","status":"publish","type":"page","link":"https:\/\/nica.network\/it\/tohuwabohu\/","title":{"rendered":"Hullabaloo"},"content":{"rendered":"<div class=\"wp-block-group is-style-default has-base-color has-accent-1-background-color has-text-color has-background has-link-color wp-elements-fa413958539b855671b21daaa84d742e is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-d445cf74 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill tickets\"><a class=\"wp-block-button__link wp-element-button\" href=\"#tickets\" style=\"padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--30)\">Direttamente ai biglietti<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\" style=\"margin-bottom:-15px;font-style:normal;font-weight:1000\"><strong>01.-04.10.2026<\/strong><\/p>\n\n\n<h1 class=\"wp-block-post-title\">Hullabaloo<\/h1>\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\" style=\"font-style:normal;font-weight:100\">Convenzione artistica a Halle (Saale)<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-keule\"\/>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">4 giorni di giocoleria e acrobazia<\/h3>\n\n\n\n<p>Sta accadendo di nuovo! Molte persone si riuniscono per celebrare le aree pi\u00f9 diverse del circo e dell'arte.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04324071538&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04324071538\" class=\"wp-block-image size-full is-style-rounded wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"873\" height=\"503\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/tohu-toss-up.webp\" alt=\"Immagine del TossUp (tutti lanciano cose in aria) di Tohuwabohu 2024\" class=\"wp-image-678\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/tohu-toss-up.webp 873w, https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/tohu-toss-up-300x173.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/tohu-toss-up-768x443.webp 768w, https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/tohu-toss-up-18x10.webp 18w\" sizes=\"auto, (max-width: 873px) 100vw, 873px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04324071c49&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04324071c49\" class=\"wp-block-image size-large is-style-rounded wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"758\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/map-location-tohuwabohu-convention-1024x758.webp\" alt=\"Mappa con la sezione locale della palestra.\" class=\"wp-image-680\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/map-location-tohuwabohu-convention-1024x758.webp 1024w, https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/map-location-tohuwabohu-convention-300x222.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/map-location-tohuwabohu-convention-768x569.webp 768w, https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/map-location-tohuwabohu-convention-16x12.webp 16w, https:\/\/nica.network\/wp-content\/uploads\/2025\/01\/map-location-tohuwabohu-convention.webp 1333w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Posizione<\/strong><\/h3>\n\n\n\n<p>Palazzetto dello sport Brandberge<br>Kreuzvorwerk 30<br>06120 Halle (Saale)<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/osm.org\/go\/0ME6osAxp\">Openstreetmap<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/maps.app.goo.gl\/n5tMtKkMK6RrgBZm8\">Google Maps<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-keule\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Il programma (ancora in fase di pianificazione)<\/h3>\n\n\n\n<ul class=\"wp-block-list is-style-checkmark-list\">\n<li><strong>Spazio del fuoco <\/strong>- Da gioved\u00ec a sabato dalle 21:00 alle 01:00<\/li>\n\n\n\n<li><strong>Rinnegato <\/strong>- Gioved\u00ec 20:00 - portate con voi l'acrobazia pi\u00f9 spettacolare o il trucco pi\u00f9 divertente della festa <\/li>\n\n\n\n<li><strong>Palcoscenico aperto<\/strong> - Venerd\u00ec 20:00<\/li>\n\n\n\n<li><strong>Giochi della convenzione<\/strong> - Domenica 13:00<\/li>\n\n\n\n<li>Un bel po' di <strong>Laboratori,<\/strong> che portate con voi!<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Le possibilit\u00e0<\/h3>\n\n\n\n<ul class=\"wp-block-list is-style-checkmark-list\">\n<li>Punti di sospensione pneumatica<\/li>\n\n\n\n<li>100m\u00b2 <strong>Acrospazio<\/strong><\/li>\n\n\n\n<li>Sala gigantesca con ampi spazi tra le 7.00 e le 22.00. La sala da ballo e la sala per gli esercizi sono aperte 24 ore su 24.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-spagat\"\/>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-4.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"786\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-4-150x150.webp\" alt=\"\" class=\"wp-image-786\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-4-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-4-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-4-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-5.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"790\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-5-150x150.webp\" alt=\"\" class=\"wp-image-790\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-5-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-5-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-5-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-6.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"789\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-6-150x150.webp\" alt=\"\" class=\"wp-image-789\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-6-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-6-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-6-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-13.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"797\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-13-150x150.webp\" alt=\"\" class=\"wp-image-797\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-13-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-13-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-13-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-8.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"793\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-8-150x150.webp\" alt=\"\" class=\"wp-image-793\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-8-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-8-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-8-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-9.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"792\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-9-150x150.webp\" alt=\"\" class=\"wp-image-792\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-9-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-9-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-9-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53459979346904300261.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"800\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53459979346904300261-1024x768.jpg\" alt=\"\" class=\"wp-image-800\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53459979346904300261-1024x768.jpg 1024w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53459979346904300261-300x225.jpg 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53459979346904300261-768x576.jpg 768w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53459979346904300261-16x12.jpg 16w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53459979346904300261.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53461911566791424051.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"799\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53461911566791424051-150x150.jpg\" alt=\"\" class=\"wp-image-799\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53461911566791424051-150x150.jpg 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53461911566791424051-300x300.jpg 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/53461911566791424051-500x500.jpg 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-2.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"785\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-2-150x150.webp\" alt=\"\" class=\"wp-image-785\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-2-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-2-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-2-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"788\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-1-150x150.webp\" alt=\"\" class=\"wp-image-788\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-1-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-1-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-1-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-10.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"794\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-10-150x150.webp\" alt=\"\" class=\"wp-image-794\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-10-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-10-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-10-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-11.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"795\" src=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-11-150x150.webp\" alt=\"\" class=\"wp-image-795\" srcset=\"https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-11-150x150.webp 150w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-11-300x300.webp 300w, https:\/\/nica.network\/wp-content\/uploads\/2025\/07\/Tohuwabohu-Convention-Halle-Saale-11-500x500.webp 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-keule\"\/>\n\n\n\n<div class=\"wp-block-group is-style-framed is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Laboratori<\/h3>\n\n\n\n<p>Naturalmente, Tohuwabohu vive anche dei laboratori che portate con voi. Ci sar\u00e0 un ampio calendario a cui saranno allegati tutti i laboratori. Ci aspettiamo una vasta gamma di aree circensi e artistiche diverse - per principianti e avanzati. Laboratori guidati o semplicemente uno scambio di conoscenze. Creiamo insieme un'offerta bella e colorata.<\/p>\n\n\n\n<p>Se avete domande o bisogno di aiuto per la pianificazione, scriveteci:<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-fc4fd283 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--4\"><a class=\"wp-block-button__link wp-element-button\" href=\"mailto:tohuwabohu.halle@outlook.de\">tohuwabohu.halle@outlook.de<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-spagat\"\/>\n\n\n\n<h3 class=\"wp-block-heading is-style-default\">Ristorazione, alloggio e viaggi<\/h3>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Com'\u00e8 la situazione del sonno?<\/summary>\n<p>Sono disponibili un massimo di 300 posti per la notte (<strong>2 dormitori e campeggio<\/strong>). <br><\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>E il cibo?<\/summary>\n<p class=\"is-style-default\"><strong>La colazione e la cena sono incluse nel prezzo<\/strong>vegetariani e vegani. Cerchiamo di mantenere l'offerta il pi\u00f9 varia possibile, ma se avete intolleranze\/allergie particolari, vi preghiamo di portare con voi qualcosa per sicurezza.<\/p>\n\n\n\n<p>Non ci \u00e8 permesso mangiare nei corridoi, ci sono stanze\/aree extra per questo. Questo \u00e8 chiaro ;). <br>Si prega di non utilizzare fornelli o barbecue a gas.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Dove posso parcheggiare la mia auto\/WoMo?<\/summary>\n<p>La palestra ha un <strong>Parcheggio senza allacciamento elettrico e idrico<\/strong>. Ci sono solo pochi posti auto direttamente adiacenti alla sala. A nord del palazzetto dello sport Brandberge (all'estremit\u00e0 settentrionale del campo sportivo) c'\u00e8 un parcheggio pubblico che pu\u00f2 essere utilizzato per parcheggiare l'auto. Il parcheggio adiacente al palazzetto dello sport di Brandberge \u00e8 riservato agli artisti del gala, all'equipaggio e alle persone con difficolt\u00e0 di deambulazione\/disabilit\u00e0 fisiche. Vi chiediamo pertanto di mantenere libero questo parcheggio. Ci sono 20 posti auto che possono essere acquistati tramite il sistema di biglietti.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Dove si trova la fermata del tram pi\u00f9 vicina?<\/summary>\n<p>La fermata del tram pi\u00f9 vicina si chiama <strong>Via Schwucht<\/strong>.<\/p>\n<\/details>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-keule\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Intorno al convegno<\/h3>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ma cosa succede a questa convention?<\/summary>\n<p>Per tutti i neofiti: per quattro giorni (da gioved\u00ec a domenica), Halle sar\u00e0 un punto di incontro e di scambio per giocolieri, acrobati, equilibristi, giocatori di diabolo, devilstick e poi provenienti da tutto il mondo. Guardare e trarre ispirazione va benissimo, ma la convention si basa sulla partecipazione e sulla sperimentazione. \u00c8 bene che abbiate con voi la vostra attrezzatura, ma ce n'\u00e8 anche in loco e, se lo chiedete gentilmente, potete prendere in prestito molto da altri. <br>L'offerta di laboratori \u00e8 ampia e sar\u00e0 esposta in loco e potr\u00e0 e dovr\u00e0 essere ampliata da tutti!<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Cosa si pu\u00f2 allenare in quali momenti e dove?<\/summary>\n<p>Il palazzetto dello sport Brandberge sar\u00e0 aperto dalle 07:00 alle 22:00. Il Firespace sar\u00e0 aperto dalle 21:00 all'01:00. Inoltre, la sala da ballo e la sala di ginnastica della SV Halle saranno aperte per tutto il periodo della convention, cos\u00ec come l'area esterna della SV Halle.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Come \u00e8 nato il Tohuwabohu?<\/summary>\n<p>La parola \"Tohuwabohu\" deriva dall'ebraico e significa pi\u00f9 o meno \"caos\". Quando i giocolieri di Halle si sono riuniti per la prima volta nel 1996, cercavano un luogo dove incontrarsi e scambiarsi idee, un posto dove stare insieme e preparare gli spettacoli. Fu cos\u00ec che nacque il Tohuwabohu-Caf\u00e9, un piccolo e accogliente locale dove non solo si potevano gustare bevande e spuntini, ma anche esibirsi sul palco aperto, provare gli oggetti di giocoleria e persino acquistarli. Il Tohuwabohu divenne rapidamente il luogo d'incontro preferito da un'ampia variet\u00e0 di artisti e dai loro amici. Purtroppo il caff\u00e8 non esiste pi\u00f9, ma il suo spirito deve continuare a vivere. Per questo dal 2014 viene organizzata ad Halle la Convention Tohuwabohu, dove gli appassionati di circo e di tutte le discipline possono sfogarsi nell'ambito di un festival che dura diversi giorni.<\/p>\n\n\n\n<p>Dal 2019, Tohuwabohu Halle \u00e8 organizzata come associazione senza scopo di lucro (Tohuwabohu Halle e.V.).<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Cosa succede fuori dal congresso?<\/summary>\n<p>Il Tohuwabohu e.V. non organizza solo la convention, ma anche altri eventi per giocolieri, acrobati e tutti i settori correlati, come la giocoleria di Babbo Natale o una regolare sessione di allenamento aperta ogni domenica.<\/p>\n\n\n\n<p>Stiamo anche lavorando per ampliare il nostro programma per bambini e giovani. Organizziamo regolarmente diversi laboratori e progetti di vacanza con bambini e giovani. La banca Saalesparkasse ci ha fornito dei fondi a questo scopo, che abbiamo utilizzato per acquistare attrezzature per la giocoleria.<\/p>\n\n\n\n<p>In futuro, abbiamo in programma di ampliare la nostra attenzione e di rendere la giocoleria e le attivit\u00e0 circensi correlate pi\u00f9 inclusive.&nbsp;<\/p>\n<\/details>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-keule\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Biglietti e ingresso<\/h3>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Qual \u00e8 la scadenza per la pre-registrazione?<\/summary>\n<p>\u00c8 possibile acquistare i biglietti online al prezzo di prevendita fino al 15\/08\/2025 incluso. Dal 16 agosto 2025, i biglietti saranno disponibili solo con un supplemento caos di 10 euro. I biglietti giornalieri sono disponibili online in qualsiasi momento e in loco fino a esaurimento scorte. I viaggiatori dell'ultimo minuto riceveranno i biglietti all-inclusive in loco, se ancora disponibili, sempre con un supplemento per il caos.<br>Siamo sempre contenti se i biglietti vengono acquistati in anticipo, in modo da poter essere rilassati e preparati nella nostra pianificazione generale \ud83d\ude09<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ci sono sconti per gruppi o sconti per gruppi circensi?<\/summary>\n<p>Se desiderate partecipare come gruppo, contattateci direttamente: troveremo sicuramente una soluzione.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Posso restituire un biglietto gi\u00e0 pagato in caso di malattia, ad esempio?<\/summary>\n<p>In caso di malattia e di impossibilit\u00e0 a partecipare, vi preghiamo di contattarci tramite il nostro modulo di contatto in modo da potervi contattare. Se tutti i biglietti sono gi\u00e0 stati venduti e c'\u00e8 gi\u00e0 una lista d'attesa per i biglietti, faremo il possibile per cedervi il vostro biglietto.&nbsp;<\/p>\n\n\n\n<p>In caso contrario, si applicano le norme di legge. In altre parole, il diritto di recesso secondo le istruzioni.<\/p>\n\n\n\n<p>Si prega di comprendere che non possiamo prendere in considerazione le cancellazioni ricevute il primo giorno del congresso o successivamente.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Sono minorenne, posso partecipare lo stesso?<\/summary>\n<p>S\u00ec, ma dovete essere accompagnati da un adulto: se non si tratta di uno dei vostri genitori, avrete bisogno di un certificato di genitore\/tutore.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ingresso per gli animali domestici?<\/summary>\n<p>Purtroppo non in linea di principio. Gli animali domestici non sono ammessi in loco. In particolare, i cani non sono ammessi sul terreno della SV Halle o sul terreno del palazzetto dello sport Brandberge.<\/p>\n<\/details>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50)\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"tickets\">I biglietti per Tohu 2026 non sono ancora disponibili. Torna a trovarci tra qualche settimana o iscriviti alla newsletter ;*<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/nica.network\/it\/newsletter\/\">Newsletter<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-keule\"\/>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--5\"><a class=\"wp-block-button__link wp-element-button\" href=\"mailto:tohuwabohu.halle@outlook.de\">tohuwabohu.halle@outlook.de<\/a><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>01.-04.10.2026 Artistik Convention in Halle (Saale) 4 Tage Jonglage &amp; Akrobatik Es passiert wieder! Viele Menschen kommen zusammen, um die verschiedensten Bereiche von Zirkus und Artistik zu feiern. Location Sporthalle BrandbergeKreuzvorwerk 3006120 Halle (Saale) Das Programm (noch in der Planung) Die M\u00f6glichkeiten Workshops Nat\u00fcrlich lebt auch die Tohuwabohu von den Workshops, die ihr mitbringt. Es [&hellip;]<\/p>\n","protected":false},"author":88,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-525","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/pages\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/comments?post=525"}],"version-history":[{"count":35,"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/pages\/525\/revisions"}],"predecessor-version":[{"id":1326,"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/pages\/525\/revisions\/1326"}],"wp:attachment":[{"href":"https:\/\/nica.network\/it\/wp-json\/wp\/v2\/media?parent=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}